{"id":352708,"date":"2026-07-02T10:01:22","date_gmt":"2026-07-02T10:01:22","guid":{"rendered":"https:\/\/hotelkalura.com\/?post_type=product&#038;p=352708"},"modified":"2026-07-06T12:40:12","modified_gmt":"2026-07-06T12:40:12","slug":"fiori-di-caldura","status":"publish","type":"product","link":"https:\/\/hotelkalura.com\/it\/shop\/fiori-di-caldura\/","title":{"rendered":"Shampoo &#8220;Fiori di Caldura&#8221;"},"content":{"rendered":"<p><strong>Shampoo<\/strong><\/p>\n<p>Uno shampoo naturale che dona ai capelli morbidezza, luminosit\u00e0 e vitalit\u00e0 grazie all\u2019estratto di camomilla e all\u2019avena bio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Fiori di Caldura<\/strong> nasce per portare il mare di Cefal\u00f9 nei tuoi capelli: una formula vegetale a base di estratto di camomilla e avena biologica che scioglie la salsedine, calma il cuoio capelluto e restituisce ad ogni ciocca la sua morbidezza naturale, lavaggio dopo lavaggio.<\/p>\n<p>La <strong>camomilla<\/strong> illumina e ammorbidisce, l&#8217;<strong>avena bio <\/strong>calma e protegge, mentre il <strong>pantenolo<\/strong> (Provitamina B5) scende in profondit\u00e0 per riparare, idratare e sigillare le cuticole, lasciando i capelli elastici e luminosi.<\/p>\n<p><strong>Il suo profumo<\/strong> parte con note di menta, mandarino, pompelmo e bergamotto. Poi si apre su note erbacee e floreali di ciclamino, t\u00e8, mughetto, violetta e rosmarino. Infine, si posa su note speziate e avvolgenti, come muschio, legno di guaiaco e legni dolci.<\/p>\n","protected":false},"featured_media":352806,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[71],"product_tag":[],"class_list":{"0":"post-352708","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-beauty","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shampoo &quot;Fiori di Caldura&quot; - Hotel Kalura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelkalura.com\/it\/shop\/fiori-di-caldura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shampoo &quot;Fiori di Caldura&quot; - Hotel Kalura\" \/>\n<meta property=\"og:description\" content=\"Fiori di Caldura nasce per portare il mare di Cefal\u00f9 nei tuoi capelli: una formula vegetale a base di estratto di camomilla e avena biologica che scioglie la salsedine, calma il cuoio capelluto e restituisce ad ogni ciocca la sua morbidezza naturale, lavaggio dopo lavaggio.  La camomilla illumina e ammorbidisce, l&#039;avena bio calma e protegge, mentre il pantenolo (Provitamina B5) scende in profondit\u00e0 per riparare, idratare e sigillare le cuticole, lasciando i capelli elastici e luminosi.  Il suo profumo parte con note di menta, mandarino, pompelmo e bergamotto. Poi si apre su note erbacee e floreali di ciclamino, t\u00e8, mughetto, violetta e rosmarino. Infine, si posa su note speziate e avvolgenti, come muschio, legno di guaiaco e legni dolci.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelkalura.com\/it\/shop\/fiori-di-caldura\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Kalura\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T12:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotelkalura.com\/wp-content\/uploads\/2026\/07\/Kalura_Beauty_shampoo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/\",\"url\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/\",\"name\":\"Shampoo \\\"Fiori di Caldura\\\" - Hotel Kalura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hotelkalura.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Kalura_Beauty_shampoo.jpg\",\"datePublished\":\"2026-07-02T10:01:22+00:00\",\"dateModified\":\"2026-07-06T12:40:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hotelkalura.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Kalura_Beauty_shampoo.jpg\",\"contentUrl\":\"https:\\\/\\\/hotelkalura.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Kalura_Beauty_shampoo.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/shop\\\/fiori-di-caldura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotelkalura.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/hotelkalura.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shampoo &#8220;Fiori di Caldura&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#website\",\"url\":\"https:\\\/\\\/hotelkalura.com\\\/\",\"name\":\"Hotel Kalura\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotelkalura.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#organization\",\"name\":\"Hotel Kalura\",\"url\":\"https:\\\/\\\/hotelkalura.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotelkalura.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Kalura_marchio.svg\",\"contentUrl\":\"https:\\\/\\\/hotelkalura.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Kalura_marchio.svg\",\"width\":1330,\"height\":475,\"caption\":\"Hotel Kalura\"},\"image\":{\"@id\":\"https:\\\/\\\/hotelkalura.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shampoo \"Fiori di Caldura\" - Hotel Kalura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelkalura.com\/it\/shop\/fiori-di-caldura\/","og_locale":"it_IT","og_type":"article","og_title":"Shampoo \"Fiori di Caldura\" - Hotel Kalura","og_description":"Fiori di Caldura nasce per portare il mare di Cefal\u00f9 nei tuoi capelli: una formula vegetale a base di estratto di camomilla e avena biologica che scioglie la salsedine, calma il cuoio capelluto e restituisce ad ogni ciocca la sua morbidezza naturale, lavaggio dopo lavaggio.  La camomilla illumina e ammorbidisce, l'avena bio calma e protegge, mentre il pantenolo (Provitamina B5) scende in profondit\u00e0 per riparare, idratare e sigillare le cuticole, lasciando i capelli elastici e luminosi.  Il suo profumo parte con note di menta, mandarino, pompelmo e bergamotto. Poi si apre su note erbacee e floreali di ciclamino, t\u00e8, mughetto, violetta e rosmarino. Infine, si posa su note speziate e avvolgenti, come muschio, legno di guaiaco e legni dolci.","og_url":"https:\/\/hotelkalura.com\/it\/shop\/fiori-di-caldura\/","og_site_name":"Hotel Kalura","article_modified_time":"2026-07-06T12:40:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2026\/07\/Kalura_Beauty_shampoo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/","url":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/","name":"Shampoo \"Fiori di Caldura\" - Hotel Kalura","isPartOf":{"@id":"https:\/\/hotelkalura.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/#primaryimage"},"image":{"@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/#primaryimage"},"thumbnailUrl":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2026\/07\/Kalura_Beauty_shampoo.jpg","datePublished":"2026-07-02T10:01:22+00:00","dateModified":"2026-07-06T12:40:12+00:00","breadcrumb":{"@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/#primaryimage","url":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2026\/07\/Kalura_Beauty_shampoo.jpg","contentUrl":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2026\/07\/Kalura_Beauty_shampoo.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/hotelkalura.com\/shop\/fiori-di-caldura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelkalura.com\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/hotelkalura.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Shampoo &#8220;Fiori di Caldura&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/hotelkalura.com\/#website","url":"https:\/\/hotelkalura.com\/","name":"Hotel Kalura","description":"","publisher":{"@id":"https:\/\/hotelkalura.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelkalura.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hotelkalura.com\/#organization","name":"Hotel Kalura","url":"https:\/\/hotelkalura.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hotelkalura.com\/#\/schema\/logo\/image\/","url":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2024\/07\/Kalura_marchio.svg","contentUrl":"https:\/\/hotelkalura.com\/wp-content\/uploads\/2024\/07\/Kalura_marchio.svg","width":1330,"height":475,"caption":"Hotel Kalura"},"image":{"@id":"https:\/\/hotelkalura.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/product\/352708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/comments?post=352708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/media\/352806"}],"wp:attachment":[{"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/media?parent=352708"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/product_brand?post=352708"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/product_cat?post=352708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hotelkalura.com\/it\/wp-json\/wp\/v2\/product_tag?post=352708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}